{"id":761,"date":"2019-09-03T10:23:38","date_gmt":"2019-09-03T03:23:38","guid":{"rendered":"https:\/\/efip.ctu.edu.vn\/web\/?p=761"},"modified":"2020-07-03T19:46:14","modified_gmt":"2020-07-03T12:46:14","slug":"renforcer-ses-competences-orthographiques","status":"publish","type":"post","link":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/","title":{"rendered":"Renforcer ses comp\u00e9tences orthographiques"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"785\" height=\"441\" src=\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png\" alt=\"\" class=\"wp-image-762\" srcset=\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png 785w, https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho-300x169.png 300w, https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho-768x431.png 768w, https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho-110x62.png 110w, https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho-420x236.png 420w, https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho-248x138.png 248w, https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho-765x430.png 765w\" sizes=\"(max-width: 785px) 100vw, 785px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Vous voulez am\u00e9liorer votre orthographe, alors ce cours en ligne est pour vous ! <strong>Nous pouvons vous aider \u00e0 r\u00e9ussir : n&#8217;h\u00e9sitez pas \u00e0 prendre rendez-vous avec l&#8217;\u00e9quipe de l&#8217;EFIP pour suivre notre tutorat. C&#8217;est gratuit pour les \u00e9tudiants de CTU et pour les enseignants francophones !<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce cours s\u2019adresse \u00e0 tout francophone, \u00e9tudiant ou professionnel, d\u00e9sireux d\u2019am\u00e9liorer ses comp\u00e9tences en orthographe, ainsi qu\u2019\u00e0 toute personne qui s\u2019int\u00e9resse \u00e0 la langue fran\u00e7aise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;absence d&#8217;une ma\u00eetrise correcte de l&#8217;orthographe peut \u00eatre un frein, voire un r\u00e9el handicap dans toute situation de r\u00e9daction, tant \u00e0 l&#8217;universit\u00e9 que dans le monde du travail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ce cours en ligne abordera les notions \u00e9l\u00e9mentaires les plus probl\u00e9matiques<\/strong>\u00a0de l&#8217;orthographe fran\u00e7aise, selon un inventaire des fautes les plus fr\u00e9quemment r\u00e9alis\u00e9es par les \u00e9tudiants universitaires. Il s&#8217;agit de\u00a0<strong>se concentrer sur les questions que l\u2019on se pose au quotidien<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;est par la r\u00e9p\u00e9tition qu&#8217;on int\u00e8gre le mieux l&#8217;orthographe ! Ainsi, l\u2019apprenant pourra \u00e9valuer et renforcer son niveau de ma\u00eetrise de l\u2019orthographe gr\u00e2ce aux nombreux exercices (d&#8217;appropriation, auto-formatifs ou encore de r\u00e9vision) propos\u00e9s tout au long du MOOC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le MOOC se d\u00e9roule sur 4 semaines de cours et d&#8217;une semaine de r\u00e9vision. Elle est constitu\u00e9e d&#8217;un ensemble de ressources p\u00e9dagogiques :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Vid\u00e9os enrichies<\/strong>&nbsp;de l&#8217;enseignant (avec sous-titrage, transcription textuelle et exercices d&#8217;appropriation interactifs)<\/li><li><strong>Fiches m\u00e9mo<\/strong>, r\u00e9sum\u00e9s du cours sous forme de sch\u00e9mas, liste de mots, etc.<\/li><li><strong>Exercices auto-formatifs<\/strong>&nbsp;: QCM, textes \u00e0 trous, &#8220;Vrai ou faux ?&#8221;, etc.<\/li><li><strong>Exercices de r\u00e9vision<\/strong>&nbsp;destin\u00e9s \u00e0 mieux ancrer vos connaissances sur le long terme<\/li><li><strong>Forums de discussion th\u00e9matiques<\/strong>&nbsp;anim\u00e9s par l&#8217;\u00e9quipe techno-p\u00e9dagogique.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Un&nbsp;<strong>forum g\u00e9n\u00e9ral<\/strong>&nbsp;et un&nbsp;<strong>glossaire participatif<\/strong>&nbsp;contribuent \u00e9galement \u00e0 la co-construction des connaissances entre apprenants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, chaque semaine fait l\u2019objet d\u2019une validation des acquis, sous forme de QCM ou d&#8217;\u00e9valuation par les pairs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus d&#8217;informations sur ce cours en ligne gratuit :<a href=\"https:\/\/www.fun-mooc.fr\/courses\/course-v1:unicaen+48002+session03\/about\"> https:\/\/www.fun-mooc.fr\/courses\/course-v1:unicaen+48002+session03\/about<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous voulez am\u00e9liorer votre orthographe, alors ce cours en ligne est pour vous ! Nous pouvons vous aider \u00e0 r\u00e9ussir &hellip; <br \/><a href=\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Renforcer ses comp\u00e9tences orthographiques<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,68],"tags":[],"class_list":["post-761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-de-l-efip","category-formation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Renforcer ses comp\u00e9tences orthographiques - EFIP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renforcer ses comp\u00e9tences orthographiques - EFIP\" \/>\n<meta property=\"og:description\" content=\"Vous voulez am\u00e9liorer votre orthographe, alors ce cours en ligne est pour vous ! Nous pouvons vous aider \u00e0 r\u00e9ussir &hellip; Continue reading Renforcer ses comp\u00e9tences orthographiques\" \/>\n<meta property=\"og:url\" content=\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\" \/>\n<meta property=\"og:site_name\" content=\"EFIP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/efipCanTho\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-03T03:23:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-03T12:46:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png\" \/>\n\t<meta property=\"og:image:width\" content=\"785\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Renforcer ses comp\u00e9tences orthographiques\",\"datePublished\":\"2019-09-03T03:23:38+00:00\",\"dateModified\":\"2020-07-03T12:46:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png\",\"articleSection\":[\"Actualit\u00e9s de l'EFIP\",\"Formation\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\",\"url\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\",\"name\":\"Renforcer ses comp\u00e9tences orthographiques - EFIP\",\"isPartOf\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png\",\"datePublished\":\"2019-09-03T03:23:38+00:00\",\"dateModified\":\"2020-07-03T12:46:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage\",\"url\":\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png\",\"contentUrl\":\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png\",\"width\":785,\"height\":441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/efip.ctu.edu.vn\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renforcer ses comp\u00e9tences orthographiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/#website\",\"url\":\"https:\/\/efip.ctu.edu.vn\/web\/\",\"name\":\"EFIP de Can Tho\",\"description\":\"Espace Francophone d&#039;Innovation et de Partenariat\",\"publisher\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/efip.ctu.edu.vn\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/#organization\",\"name\":\"EFIP\",\"url\":\"https:\/\/efip.ctu.edu.vn\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2025\/05\/efip2-150x89-1.jpg\",\"contentUrl\":\"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2025\/05\/efip2-150x89-1.jpg\",\"width\":150,\"height\":89,\"caption\":\"EFIP\"},\"image\":{\"@id\":\"https:\/\/efip.ctu.edu.vn\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/efipCanTho\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/efip.ctu.edu.vn\/web\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renforcer ses comp\u00e9tences orthographiques - EFIP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/","og_locale":"en_US","og_type":"article","og_title":"Renforcer ses comp\u00e9tences orthographiques - EFIP","og_description":"Vous voulez am\u00e9liorer votre orthographe, alors ce cours en ligne est pour vous ! Nous pouvons vous aider \u00e0 r\u00e9ussir &hellip; Continue reading Renforcer ses comp\u00e9tences orthographiques","og_url":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/","og_site_name":"EFIP","article_publisher":"https:\/\/www.facebook.com\/efipCanTho","article_published_time":"2019-09-03T03:23:38+00:00","article_modified_time":"2020-07-03T12:46:14+00:00","og_image":[{"width":785,"height":441,"url":"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#article","isPartOf":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/"},"author":{"name":"","@id":""},"headline":"Renforcer ses comp\u00e9tences orthographiques","datePublished":"2019-09-03T03:23:38+00:00","dateModified":"2020-07-03T12:46:14+00:00","mainEntityOfPage":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/#organization"},"image":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage"},"thumbnailUrl":"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png","articleSection":["Actualit\u00e9s de l'EFIP","Formation"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/","url":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/","name":"Renforcer ses comp\u00e9tences orthographiques - EFIP","isPartOf":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage"},"image":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage"},"thumbnailUrl":"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png","datePublished":"2019-09-03T03:23:38+00:00","dateModified":"2020-07-03T12:46:14+00:00","breadcrumb":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#primaryimage","url":"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png","contentUrl":"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2019\/09\/CompOrtho.png","width":785,"height":441},{"@type":"BreadcrumbList","@id":"https:\/\/efip.ctu.edu.vn\/web\/renforcer-ses-competences-orthographiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/efip.ctu.edu.vn\/web\/"},{"@type":"ListItem","position":2,"name":"Renforcer ses comp\u00e9tences orthographiques"}]},{"@type":"WebSite","@id":"https:\/\/efip.ctu.edu.vn\/web\/#website","url":"https:\/\/efip.ctu.edu.vn\/web\/","name":"EFIP de Can Tho","description":"Espace Francophone d&#039;Innovation et de Partenariat","publisher":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/efip.ctu.edu.vn\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/efip.ctu.edu.vn\/web\/#organization","name":"EFIP","url":"https:\/\/efip.ctu.edu.vn\/web\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/efip.ctu.edu.vn\/web\/#\/schema\/logo\/image\/","url":"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2025\/05\/efip2-150x89-1.jpg","contentUrl":"https:\/\/efip.ctu.edu.vn\/web\/wp-content\/uploads\/2025\/05\/efip2-150x89-1.jpg","width":150,"height":89,"caption":"EFIP"},"image":{"@id":"https:\/\/efip.ctu.edu.vn\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/efipCanTho"]},{"@type":"Person","@id":"","url":"https:\/\/efip.ctu.edu.vn\/web\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/posts\/761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/comments?post=761"}],"version-history":[{"count":4,"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/posts\/761\/revisions"}],"predecessor-version":[{"id":766,"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/posts\/761\/revisions\/766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/media\/762"}],"wp:attachment":[{"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/media?parent=761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/categories?post=761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efip.ctu.edu.vn\/web\/wp-json\/wp\/v2\/tags?post=761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}